{"id":4162,"date":"2024-03-19T17:05:56","date_gmt":"2024-03-19T17:05:56","guid":{"rendered":"http:\/\/localhost\/www\/?page_id=4162"},"modified":"2024-09-04T15:12:36","modified_gmt":"2024-09-04T15:12:36","slug":"equipo-directivo","status":"publish","type":"page","link":"https:\/\/www.utopiafiber.dev\/es\/equipo-directivo\/","title":{"rendered":"Conozca a los ejecutivos"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"4162\" class=\"elementor elementor-4162\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ccd45c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1ccd45c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_widescreen&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_laptop&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-34dd2ed\" data-id=\"34dd2ed\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0afaa8 elementor-widget elementor-widget-spacer\" data-id=\"e0afaa8\" data-element_type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7fcfe17 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7fcfe17\" data-element_type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_widescreen&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_laptop&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4e6905d\" data-id=\"4e6905d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df30ef8 wdt-heading-style-03 elementor-invisible elementor-widget elementor-widget-wdt-heading\" data-id=\"df30ef8\" data-element_type=\"widget\" data-settings=\"{&quot;wdt_enable_inview_status&quot;:&quot;true&quot;,&quot;split_heading&quot;:&quot;true&quot;,&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder\" id=\"wdt-heading-df30ef8\"><h2 class=\"wdt-heading-title-wrapper wdt-heading-align- wdt-heading-deco-wrapper\"><span class=\"wdt-heading-title\">Conoce UTOPIA Fiber's <span class=\"wdt-split-heading-wrapper\"><span class=\"wdt-split-heading-title\">E<\/span><span class=\"wdt-split-heading-title\">x<\/span><span class=\"wdt-split-heading-title\">e<\/span><span class=\"wdt-split-heading-title\">c<\/span><span class=\"wdt-split-heading-title\">u<\/span><span class=\"wdt-split-heading-title\">t<\/span><span class=\"wdt-split-heading-title\">i<\/span><span class=\"wdt-split-heading-title\">v<\/span><span class=\"wdt-split-heading-title\">e<\/span><\/span><span class=\"wdt-split-heading-wrapper\"><span class=\"wdt-split-heading-title\">T<\/span><span class=\"wdt-split-heading-title\">e<\/span><span class=\"wdt-split-heading-title\">a<\/span><span class=\"wdt-split-heading-title\">m<\/span><\/span><\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-45a0936 elementor-widget elementor-widget-spacer\" data-id=\"45a0936\" data-element_type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0739b4d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0739b4d\" data-element_type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_widescreen&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_laptop&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-75f4b42\" data-id=\"75f4b42\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5426a66 elementor-widget elementor-widget-spacer\" data-id=\"5426a66\" data-element_type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e44e7d7 elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e44e7d7\" data-element_type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_widescreen&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_laptop&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b3fc43d\" data-id=\"b3fc43d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3115e87 elementor-widget elementor-widget-elementskit-team\" data-id=\"3115e87\" data-element_type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\">\t\t\t\t\t\t\t\t\n\t\t<div class=\"profile-card elementor-animation- text-center ekit-team-style-default\">\n\t\t\t\t\t\t\t<a aria-label=\"perfil\" href=\"javascript:void(0)\" data-mfp-src=\"#ekit_team_modal_3115e87_4162\" class=\"ekit-team-popup\">\n\t\t\t\n\t\t\t\t<div class=\"profile-header ekit-team-img ekit-img-overlay ekit-team-img-block\"  data-toggle=\"modal\" data-target=\"ekit_team_modal_#3115e87_4162\" >\n\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1829\" src=\"https:\/\/www.utopiafiber.dev\/wp-content\/uploads\/2024\/03\/Roger-Timmerman-scaled-1.jpg\" class=\"attachment-full size-full wp-image-4166\" alt=\"\" \/>\t\t\t\t<\/div><!-- .profile-header END -->\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\n\t\t\t\t<div class=\"profile-body\">\n\t\t\t\t\t\n\t\t\t\t\t<h2 class=\"profile-title\">\n\t\t\t\t\t\t\t\t\t\t\t<a aria-label=\"perfil\" href=\"javascript:void(0)\" data-mfp-src=\"#ekit_team_modal_3115e87_4162\" class=\"ekit-team-popup\">\n\t\t\t\t\t\tROGER TIMMERMAN, \t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t<p class=\"profile-designation\">Director Ejecutivo<\/p>\n\t\t\t\t\t\t\t\t\t\t<p class=\"profile-content\">Roger ocupa el cargo de director ejecutivo de UTOPIA Fiber desde 2016 y es profesional de la gesti\u00f3n tecnol\u00f3gica en telecomunicaciones y tecnolog\u00edas de la informaci\u00f3n desde hace m\u00e1s de 15 a\u00f1os. Ha dise\u00f1ado y construido redes a lo largo de su carrera en diversas funciones, como vicepresidente de ingenier\u00eda de Vivint Wireless, director de tecnolog\u00eda de UTOPIA Fiber, ingeniero de redes de iProvo y director de productos de red de la Universidad Brigham Young. Roger se licenci\u00f3 y obtuvo un m\u00e1ster en Tecnolog\u00eda de la Informaci\u00f3n en la Universidad Brigham Young.<\/p>\n\t\t\t\t\t\t\t\t\t<\/div><!-- .profile-body END -->\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\n\t\t\t\t\t<div class=\"zoom-anim-dialog mfp-hide elementskit-team-popup team-popup-id-3115e87\" id=\"ekit_team_modal_3115e87_4162\" tabindex=\"-1\" role=\"dialog\" aria-hidden=\"true\">\n\t\t\t\t<div class=\"modal-dialog modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t<button type=\"button\" class=\"ekit-team-modal-close\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ekit-team-modal-img\">\n\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1829\" src=\"https:\/\/www.utopiafiber.dev\/wp-content\/uploads\/2024\/03\/Roger-Timmerman-scaled-1.jpg\" class=\"attachment-full size-full wp-image-4166\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"ekit-team-modal-info has-img\">\n\t\t\t\t\t\t\t\t<h2 class=\"ekit-team-modal-title\">ROGER TIMMERMAN, <\/h2>\n\t\t\t\t\t\t\t\t<p class=\"ekit-team-modal-position\">Director Ejecutivo<\/p>\n\n\t\t\t\t\t\t\t\t<div class=\"ekit-team-modal-content\">\n\t\t\t\t\t\t\t\t\tRoger ha sido Director Ejecutivo de UTOPIA Fiber desde 2016 y ha sido un profesional de la gesti\u00f3n tecnol\u00f3gica en telecomunicaciones y tecnolog\u00edas de la informaci\u00f3n durante m\u00e1s de 15 a\u00f1os. Roger ha dise\u00f1ado y construido redes a lo largo de su carrera en diversas funciones, como vicepresidente de ingenier\u00eda de Vivint Wireless, director de tecnolog\u00eda de UTOPIA Fiber, ingeniero de redes de iProvo y director de productos de red de la Universidad Brigham Young. Roger se licenci\u00f3 y obtuvo un m\u00e1ster en Tecnolog\u00eda de la Informaci\u00f3n en la Universidad Brigham Young.\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-050221e\" data-id=\"050221e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e48d51 elementor-widget elementor-widget-elementskit-team\" data-id=\"2e48d51\" data-element_type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\">\t\t\t\t\t\t\t\t\n\t\t<div class=\"profile-card elementor-animation- text-center ekit-team-style-default\">\n\t\t\t\t\t\t\t<a aria-label=\"perfil\" href=\"javascript:void(0)\" data-mfp-src=\"#ekit_team_modal_2e48d51_4162\" class=\"ekit-team-popup\">\n\t\t\t\n\t\t\t\t<div class=\"profile-header ekit-team-img ekit-img-overlay ekit-team-img-block\"  data-toggle=\"modal\" data-target=\"ekit_team_modal_#2e48d51_4162\" >\n\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1829\" src=\"https:\/\/www.utopiafiber.dev\/wp-content\/uploads\/2024\/03\/Nicole-Cottle-scaled-1.jpg\" class=\"attachment-full size-full wp-image-4169\" alt=\"\" \/>\t\t\t\t<\/div><!-- .profile-header END -->\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\n\t\t\t\t<div class=\"profile-body\">\n\t\t\t\t\t\n\t\t\t\t\t<h2 class=\"profile-title\">\n\t\t\t\t\t\t\t\t\t\t\t<a aria-label=\"perfil\" href=\"javascript:void(0)\" data-mfp-src=\"#ekit_team_modal_2e48d51_4162\" class=\"ekit-team-popup\">\n\t\t\t\t\t\tNICOLE COTTLE\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t<p class=\"profile-designation\">Director de Asuntos Gubernamentales<\/p>\n\t\t\t\t\t\t\t\t\t\t<p class=\"profile-content\">Nicole Cottle llega a UTOPIA Fiber tras 24 a\u00f1os en la administraci\u00f3n municipal, donde ha desempe\u00f1ado diversas funciones, como abogada municipal, directora de desarrollo econ\u00f3mico y comunitario, directora de relaciones gubernamentales, directora de sostenibilidad, asesora general y subdirectora municipal. Es bien conocida en el sector p\u00fablico y privado como abogada con licencia tanto en Utah como en Wyoming. Adem\u00e1s de su pr\u00e1ctica municipal civil y sus funciones de liderazgo, Nicole ha representado a clientes privados de todo el estado en las \u00e1reas de relaciones legislativas y gubernamentales, desarrollo y uso del suelo, financiaci\u00f3n de bonos, planificaci\u00f3n patrimonial y empresarial, y otras leyes transaccionales. <\/p>\n\t\t\t\t\t\t\t\t\t<\/div><!-- .profile-body END -->\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\n\t\t\t\t\t<div class=\"zoom-anim-dialog mfp-hide elementskit-team-popup team-popup-id-2e48d51\" id=\"ekit_team_modal_2e48d51_4162\" tabindex=\"-1\" role=\"dialog\" aria-hidden=\"true\">\n\t\t\t\t<div class=\"modal-dialog modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t<button type=\"button\" class=\"ekit-team-modal-close\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ekit-team-modal-img\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1829\" src=\"https:\/\/www.utopiafiber.dev\/wp-content\/uploads\/2024\/03\/Nicole-Cottle-scaled-1.jpg\" class=\"attachment-full size-full wp-image-4169\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"ekit-team-modal-info has-img\">\n\t\t\t\t\t\t\t\t<h2 class=\"ekit-team-modal-title\">NICOLE COTTLE<\/h2>\n\t\t\t\t\t\t\t\t<p class=\"ekit-team-modal-position\">Director de Asuntos Gubernamentales<\/p>\n\n\t\t\t\t\t\t\t\t<div class=\"ekit-team-modal-content\">\n\t\t\t\t\t\t\t\t\tNicole Cottle llega a UTOPIA Fiber tras 24 a\u00f1os en la administraci\u00f3n municipal, donde ha desempe\u00f1ado diversas funciones, como abogada municipal, directora de desarrollo econ\u00f3mico y comunitario, directora de relaciones gubernamentales, directora de sostenibilidad, asesora general y subdirectora municipal. Es bien conocida en el sector p\u00fablico y privado como abogada con licencia tanto en Utah como en Wyoming. Adem\u00e1s de su pr\u00e1ctica municipal civil y sus funciones de liderazgo, Nicole ha representado a clientes privados de todo el estado en las \u00e1reas de relaciones legislativas y gubernamentales, desarrollo y uso del suelo, financiaci\u00f3n de bonos, planificaci\u00f3n patrimonial y empresarial, y otras leyes transaccionales. Nicole ha participado en m\u00e1s de dos mil millones de d\u00f3lares en soluciones creativas de financiaci\u00f3n, incluyendo todo tipo de fianzas, C-Pace y PID. Consigui\u00f3 varios cientos de millones de d\u00f3lares en asignaciones, subvenciones y otros fondos para m\u00faltiples proyectos, y dirigi\u00f3 varios esfuerzos de reurbanizaci\u00f3n a gran escala valorados en m\u00e1s de dos mil millones de d\u00f3lares. Es experta en llevar los acuerdos a buen puerto, protegiendo al mismo tiempo los intereses de los implicados. Como directora de relaciones gubernamentales, ha trabajado durante 23 a\u00f1os a nivel federal, estatal y local en cientos de proyectos de ley, acciones legislativas y actividades normativas, al tiempo que ha mantenido relaciones en todos los sectores. Nicole ha formado parte de la Junta de la Agencia de Infraestructuras de Utah, del Fondo Fiduciario Olene Walker para la Vivienda, de la Junta de Pobreza Intergeneracional, de la Comisi\u00f3n de Defensa del Indigente, de varios comit\u00e9s legislativos, de la Autoridad Portuaria Interior, as\u00ed como de la Junta Ejecutiva de Operation My Hometown. Actualmente forma parte del Utah Land Use Institute, la Our Hometown Foundation y acaba de ser nombrada Comandante Honoraria del Ala de Caza 388 de la Base A\u00e9rea de Hill.\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2a4795d\" data-id=\"2a4795d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed5f7f2 elementor-widget elementor-widget-elementskit-team\" data-id=\"ed5f7f2\" data-element_type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\">\t\t\t\t\t\t\t\t\n\t\t<div class=\"profile-card elementor-animation- text-center ekit-team-style-default\">\n\t\t\t\t\t\t\t<a aria-label=\"perfil\" href=\"javascript:void(0)\" data-mfp-src=\"#ekit_team_modal_ed5f7f2_4162\" class=\"ekit-team-popup\">\n\t\t\t\n\t\t\t\t<div class=\"profile-header ekit-team-img ekit-img-overlay ekit-team-img-block\"  data-toggle=\"modal\" data-target=\"ekit_team_modal_#ed5f7f2_4162\" >\n\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1829\" src=\"https:\/\/www.utopiafiber.dev\/wp-content\/uploads\/2024\/03\/Aaron-Leach-scaled-1.jpg\" class=\"attachment-full size-full wp-image-4170\" alt=\"\" \/>\t\t\t\t<\/div><!-- .profile-header END -->\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\n\t\t\t\t<div class=\"profile-body\">\n\t\t\t\t\t\n\t\t\t\t\t<h2 class=\"profile-title\">\n\t\t\t\t\t\t\t\t\t\t\t<a aria-label=\"perfil\" href=\"javascript:void(0)\" data-mfp-src=\"#ekit_team_modal_ed5f7f2_4162\" class=\"ekit-team-popup\">\n\t\t\t\t\t\tAARON LEACH\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t<p class=\"profile-designation\">Director de Tecnolog\u00eda<\/p>\n\t\t\t\t\t\t\t\t\t\t<p class=\"profile-content\">Aaron ha estado con UTOPIA Fiber\/UIA desde junio de 2017 y ha estado en operaciones t\u00e9cnicas, gesti\u00f3n de ingenier\u00eda y tecnolog\u00eda de la informaci\u00f3n durante m\u00e1s de 17 a\u00f1os. Comenz\u00f3 como nuestro Director de Operaciones y recientemente pas\u00f3 a ser nuestro Director de Tecnolog\u00eda cuando el puesto se dividi\u00f3 en dos. Aaron se licenci\u00f3 en Ciencias por la Universidad de Phoenix y obtuvo un m\u00e1ster en Sistemas de Informaci\u00f3n y Gesti\u00f3n Tecnol\u00f3gica por la Universidad Capella<\/p>\n\t\t\t\t\t\t\t\t\t<\/div><!-- .profile-body END -->\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\n\t\t\t\t\t<div class=\"zoom-anim-dialog mfp-hide elementskit-team-popup team-popup-id-ed5f7f2\" id=\"ekit_team_modal_ed5f7f2_4162\" tabindex=\"-1\" role=\"dialog\" aria-hidden=\"true\">\n\t\t\t\t<div class=\"modal-dialog modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t<button type=\"button\" class=\"ekit-team-modal-close\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ekit-team-modal-img\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1829\" src=\"https:\/\/www.utopiafiber.dev\/wp-content\/uploads\/2024\/03\/Aaron-Leach-scaled-1.jpg\" class=\"attachment-full size-full wp-image-4170\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"ekit-team-modal-info has-img\">\n\t\t\t\t\t\t\t\t<h2 class=\"ekit-team-modal-title\">AARON LEACH<\/h2>\n\t\t\t\t\t\t\t\t<p class=\"ekit-team-modal-position\">Director de Tecnolog\u00eda<\/p>\n\n\t\t\t\t\t\t\t\t<div class=\"ekit-team-modal-content\">\n\t\t\t\t\t\t\t\t\tAaron lleva en la UTOPIA\/UIA desde junio de 2017 y ha trabajado en operaciones t\u00e9cnicas, gesti\u00f3n de ingenier\u00eda y tecnolog\u00eda de la informaci\u00f3n durante m\u00e1s de 17 a\u00f1os. Comenz\u00f3 como nuestro Director de Operaciones y recientemente pas\u00f3 a ser nuestro Director de Tecnolog\u00eda. Aaron se licenci\u00f3 en Ciencias por la Universidad de Phoenix y obtuvo un m\u00e1ster en Sistemas de Informaci\u00f3n y Gesti\u00f3n Tecnol\u00f3gica por la Universidad Capella.\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f2ace5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f2ace5\" data-element_type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_widescreen&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_laptop&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8a15bd5\" data-id=\"8a15bd5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6aa024 elementor-widget elementor-widget-spacer\" data-id=\"f6aa024\" data-element_type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e657962 elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e657962\" data-element_type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_widescreen&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_laptop&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-44fb8c1\" data-id=\"44fb8c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f0ea34a elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f0ea34a\" data-element_type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_widescreen&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_laptop&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d3f14ac\" data-id=\"d3f14ac\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e966659 elementor-widget elementor-widget-elementskit-team\" data-id=\"e966659\" data-element_type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\">\t\t\t\t\t\t\t\t\n\t\t<div class=\"profile-card elementor-animation- text-center ekit-team-style-default\">\n\t\t\t\t\t\t\t<a aria-label=\"perfil\" href=\"javascript:void(0)\" data-mfp-src=\"#ekit_team_modal_e966659_4162\" class=\"ekit-team-popup\">\n\t\t\t\n\t\t\t\t<div class=\"profile-header ekit-team-img ekit-img-overlay ekit-team-img-block\"  data-toggle=\"modal\" data-target=\"ekit_team_modal_#e966659_4162\" >\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1829\" src=\"https:\/\/www.utopiafiber.dev\/wp-content\/uploads\/2024\/03\/Kim-McKinley-scaled-1.jpg\" class=\"attachment-full size-full wp-image-4167\" alt=\"\" \/>\t\t\t\t<\/div><!-- .profile-header END -->\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\n\t\t\t\t<div class=\"profile-body\">\n\t\t\t\t\t\n\t\t\t\t\t<h2 class=\"profile-title\">\n\t\t\t\t\t\t\t\t\t\t\t<a aria-label=\"perfil\" href=\"javascript:void(0)\" data-mfp-src=\"#ekit_team_modal_e966659_4162\" class=\"ekit-team-popup\">\n\t\t\t\t\t\tKIMBERLY MCKINLEY\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t<p class=\"profile-designation\">Jefa de Marketing y Directora Adjunta<\/p>\n\t\t\t\t\t\t\t\t\t\t<p class=\"profile-content\">Kim McKinley se incorpor\u00f3 a UTOPIA Fiber en 2010. En su funci\u00f3n de CMO, supervisa los departamentos de Marketing, Ventas, Cumplimiento de pedidos y Atenci\u00f3n al cliente. Kim tambi\u00e9n es Directora Adjunta de UTOPIA Fiber. Forma parte de los Consejos Ejecutivos de la Fiber Broadband Association y de la American Association for Public Broadband. Antes de incorporarse a UTOPIA Fiber, trabaj\u00f3 en el sector del marketing hotelero. Kim es licenciada en Administraci\u00f3n de Empresas por el College of Charleston de Charleston (Carolina del Sur).<\/p>\n\t\t\t\t\t\t\t\t\t<\/div><!-- .profile-body END -->\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\n\t\t\t\t\t<div class=\"zoom-anim-dialog mfp-hide elementskit-team-popup team-popup-id-e966659\" id=\"ekit_team_modal_e966659_4162\" tabindex=\"-1\" role=\"dialog\" aria-hidden=\"true\">\n\t\t\t\t<div class=\"modal-dialog modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t<button type=\"button\" class=\"ekit-team-modal-close\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ekit-team-modal-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1829\" src=\"https:\/\/www.utopiafiber.dev\/wp-content\/uploads\/2024\/03\/Kim-McKinley-scaled-1.jpg\" class=\"attachment-full size-full wp-image-4167\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"ekit-team-modal-info has-img\">\n\t\t\t\t\t\t\t\t<h2 class=\"ekit-team-modal-title\">KIMBERLY MCKINLEY<\/h2>\n\t\t\t\t\t\t\t\t<p class=\"ekit-team-modal-position\">Jefa de Marketing y Directora Adjunta<\/p>\n\n\t\t\t\t\t\t\t\t<div class=\"ekit-team-modal-content\">\n\t\t\t\t\t\t\t\t\tKim McKinley se incorpor\u00f3 a UTOPIA Fiber en 2010. En su funci\u00f3n de CMO, supervisa los departamentos de Marketing, Ventas, Cumplimiento de pedidos y Atenci\u00f3n al cliente. Antes de incorporarse a UTOPIA Fiber, trabaj\u00f3 en el sector del marketing hotelero en la costa este. Kim es licenciada en Administraci\u00f3n de Empresas por el College of Charleston de Charleston (Carolina del Sur).\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2cd5162\" data-id=\"2cd5162\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a2ec75 elementor-widget elementor-widget-elementskit-team\" data-id=\"6a2ec75\" data-element_type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\">\t\t\t\t\t\t\t\t\n\t\t<div class=\"profile-card elementor-animation- text-center ekit-team-style-default\">\n\t\t\t\t\t\t\t<a aria-label=\"perfil\" href=\"javascript:void(0)\" data-mfp-src=\"#ekit_team_modal_6a2ec75_4162\" class=\"ekit-team-popup\">\n\t\t\t\n\t\t\t\t<div class=\"profile-header ekit-team-img ekit-img-overlay ekit-team-img-block\"  data-toggle=\"modal\" data-target=\"ekit_team_modal_#6a2ec75_4162\" >\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1829\" src=\"https:\/\/www.utopiafiber.dev\/wp-content\/uploads\/2024\/03\/Jeff-Erwin-scaled-1.jpg\" class=\"attachment-full size-full wp-image-4165\" alt=\"\" \/>\t\t\t\t<\/div><!-- .profile-header END -->\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\n\t\t\t\t<div class=\"profile-body\">\n\t\t\t\t\t\n\t\t\t\t\t<h2 class=\"profile-title\">\n\t\t\t\t\t\t\t\t\t\t\t<a aria-label=\"perfil\" href=\"javascript:void(0)\" data-mfp-src=\"#ekit_team_modal_6a2ec75_4162\" class=\"ekit-team-popup\">\n\t\t\t\t\t\tJEFF ERWIN\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t<p class=\"profile-designation\">Director de Operaciones<\/p>\n\t\t\t\t\t\t\t\t\t\t<p class=\"profile-content\">Jeff se uni\u00f3 al equipo de UTOPIA Fiber en junio de 2021 como nuestro Director de Operaciones. Antes de unirse a UTOPIA Fiber, fue director y gerente de varias empresas tecnol\u00f3gicas y de software de todo el pa\u00eds, como Vaxess Technologies, Vivint Smart Home, Lucid Software y Smart Interests, y regres\u00f3 a Salt Lake City tras vivir varios a\u00f1os en el Reino Unido. Jeff es licenciado en Ciencias Pol\u00edticas por la Universidad de Iowa y tiene un m\u00e1ster en Gesti\u00f3n por la Universidad de Harvard.<\/p>\n\t\t\t\t\t\t\t\t\t<\/div><!-- .profile-body END -->\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\n\t\t\t\t\t<div class=\"zoom-anim-dialog mfp-hide elementskit-team-popup team-popup-id-6a2ec75\" id=\"ekit_team_modal_6a2ec75_4162\" tabindex=\"-1\" role=\"dialog\" aria-hidden=\"true\">\n\t\t\t\t<div class=\"modal-dialog modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t<button type=\"button\" class=\"ekit-team-modal-close\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ekit-team-modal-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1829\" src=\"https:\/\/www.utopiafiber.dev\/wp-content\/uploads\/2024\/03\/Jeff-Erwin-scaled-1.jpg\" class=\"attachment-full size-full wp-image-4165\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"ekit-team-modal-info has-img\">\n\t\t\t\t\t\t\t\t<h2 class=\"ekit-team-modal-title\">JEFF ERWIN<\/h2>\n\t\t\t\t\t\t\t\t<p class=\"ekit-team-modal-position\">Director de Operaciones<\/p>\n\n\t\t\t\t\t\t\t\t<div class=\"ekit-team-modal-content\">\n\t\t\t\t\t\t\t\t\tJeff se uni\u00f3 al equipo de UTOPIA Fiber en junio de 2021 como nuestro Director de Operaciones. Desde 2013 ha sido director y gerente de varias empresas tecnol\u00f3gicas y de software de todo el pa\u00eds, como Vaxess Technologies, Vivint Smart Home, Lucid Software y Smart Interests. Recientemente regres\u00f3 a Salt Lake City tras vivir varios a\u00f1os en el Reino Unido. Jeff es licenciado en Ciencias Pol\u00edticas por la Universidad de Iowa y tiene un m\u00e1ster en Gesti\u00f3n por la Universidad de Harvard.\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-df1d923\" data-id=\"df1d923\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-812be76 elementor-widget elementor-widget-elementskit-team\" data-id=\"812be76\" data-element_type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\">\t\t\t\t\t\t\t\t\n\t\t<div class=\"profile-card elementor-animation- text-center ekit-team-style-default\">\n\t\t\t\t\t\t\t<a aria-label=\"perfil\" href=\"javascript:void(0)\" data-mfp-src=\"#ekit_team_modal_812be76_4162\" class=\"ekit-team-popup\">\n\t\t\t\n\t\t\t\t<div class=\"profile-header ekit-team-img ekit-img-overlay ekit-team-img-block\"  data-toggle=\"modal\" data-target=\"ekit_team_modal_#812be76_4162\" >\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1829\" src=\"https:\/\/www.utopiafiber.dev\/wp-content\/uploads\/2024\/03\/Jason-Roberts-scaled-1.jpg\" class=\"attachment-full size-full wp-image-4168\" alt=\"\" \/>\t\t\t\t<\/div><!-- .profile-header END -->\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\n\t\t\t\t<div class=\"profile-body\">\n\t\t\t\t\t\n\t\t\t\t\t<h2 class=\"profile-title\">\n\t\t\t\t\t\t\t\t\t\t\t<a aria-label=\"perfil\" href=\"javascript:void(0)\" data-mfp-src=\"#ekit_team_modal_812be76_4162\" class=\"ekit-team-popup\">\n\t\t\t\t\t\tJASON ROBERTS\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t<p class=\"profile-designation\">Director Financiero<\/p>\n\t\t\t\t\t\t\t\t\t\t<p class=\"profile-content\">Jason empez\u00f3 a trabajar en UTOPIA Fiber en mayo de 2022 y aporta d\u00e9cadas de experiencia financiera en los sectores p\u00fablico y privado en un momento en el que UTOPIA est\u00e1 escalando r\u00e1pidamente y las cadenas de suministro y los mercados financieros est\u00e1n causando quebraderos de cabeza. Antes de incorporarse a UTOPIA Fiber, Roberts fue Administrador de Brigham City y anteriormente Director Financiero de la ciudad. Tambi\u00e9n ha trabajado como Interventor del Transportation Alliance Bank y en Ernst &amp; Young en Salt Lake City. Jason posee el t\u00edtulo de CPA y es licenciado y m\u00e1ster en contabilidad por la Universidad Estatal de Utah.<\/p>\n\t\t\t\t\t\t\t\t\t<\/div><!-- .profile-body END -->\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\n\t\t\t\t\t<div class=\"zoom-anim-dialog mfp-hide elementskit-team-popup team-popup-id-812be76\" id=\"ekit_team_modal_812be76_4162\" tabindex=\"-1\" role=\"dialog\" aria-hidden=\"true\">\n\t\t\t\t<div class=\"modal-dialog modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t<button type=\"button\" class=\"ekit-team-modal-close\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ekit-team-modal-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1829\" src=\"https:\/\/www.utopiafiber.dev\/wp-content\/uploads\/2024\/03\/Jason-Roberts-scaled-1.jpg\" class=\"attachment-full size-full wp-image-4168\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"ekit-team-modal-info has-img\">\n\t\t\t\t\t\t\t\t<h2 class=\"ekit-team-modal-title\">JASON ROBERTS<\/h2>\n\t\t\t\t\t\t\t\t<p class=\"ekit-team-modal-position\">Director Financiero<\/p>\n\n\t\t\t\t\t\t\t\t<div class=\"ekit-team-modal-content\">\n\t\t\t\t\t\t\t\t\tJason empez\u00f3 a trabajar en UTOPIA Fiber en mayo de 2022 y aporta d\u00e9cadas de experiencia financiera en los sectores p\u00fablico y privado en un momento en el que UTOPIA est\u00e1 escalando r\u00e1pidamente, y las cadenas de suministro y los mercados financieros provocan acidez. Antes de incorporarse a UTOPIA Fiber, Roberts fue Administrador de Brigham City y anteriormente ocup\u00f3 el cargo de Director Financiero de la ciudad. Tambi\u00e9n ha trabajado como Interventor del Transportation Alliance Bank y en Ernst &amp; Young en Salt Lake City. Jason tiene el t\u00edtulo de CPA y ha obtenido la licenciatura y el m\u00e1ster en Contabilidad por la Universidad Estatal de Utah.\n\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23f8b55 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23f8b55\" data-element_type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_widescreen&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_laptop&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6cedeb2\" data-id=\"6cedeb2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f09b8f elementor-widget elementor-widget-spacer\" data-id=\"7f09b8f\" data-element_type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Meet UTOPIA Fiber&#8217;s ExecutiveTeam ROGER TIMMERMAN, Executive Director Roger has been serving as UTOPIA Fiber\u2019s Executive Director since 2016 and has been a technology management professional in telecommunications and information technology for over 15 years. He has been designing and building networks throughout his career in various roles including Vice President of Engineering for Vivint [&hellip;]<\/p>","protected":false},"author":20,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-4162","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/pages\/4162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/comments?post=4162"}],"version-history":[{"count":124,"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/pages\/4162\/revisions"}],"predecessor-version":[{"id":16093,"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/pages\/4162\/revisions\/16093"}],"wp:attachment":[{"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/media?parent=4162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}