{"id":11570,"date":"2023-06-23T15:27:37","date_gmt":"2023-06-23T15:27:37","guid":{"rendered":"https:\/\/www.utopiafiber.com\/?p=11570"},"modified":"2024-04-16T09:56:55","modified_gmt":"2024-04-16T09:56:55","slug":"entrevista-con-un-director-de-ingenieria-de-planta-externa","status":"publish","type":"post","link":"https:\/\/www.utopiafiber.dev\/es\/entrevista-con-un-director-de-ingenieria-de-planta-externa\/","title":{"rendered":"Entrevista con un ingeniero de planta externo"},"content":{"rendered":"<p>Bienvenidos a la siguiente entrega de nuestra serie de entrevistas a empleados de UTOPIA Fiber. En la entrevista de hoy, hablaremos con nuestro Director de Ingenier\u00eda de Planta Exterior, Brian Kelsey, para conocer todos los detalles sobre c\u00f3mo es trabajar en el \u00e1rea de planificaci\u00f3n de redes de UTOPIA Fiber.<\/p>\n\n\n\n<p><strong>\u00bfC\u00f3mo te llamas, qu\u00e9 cargo ocupas y cu\u00e1nto tiempo llevas en UTOPIA Fiber?<\/strong><\/p>\n\n\n\n<p>Me llamo Brian Kelsey. Soy el Director de Ingenier\u00eda de Planta Exterior y llevo aqu\u00ed 6 a\u00f1os.<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 hace usted como Director de Ingenier\u00eda de Planta Externa?<\/strong><\/p>\n\n\n\n<p>Dise\u00f1amos rutas de fibra y trabajamos con empresas de ingenier\u00eda para asegurarnos de que todo est\u00e1 correctamente dise\u00f1ado con la fibra.<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 departamentos gestiona en UTOPIA Fiber?<\/strong><\/p>\n\n\n\n<p>Mi equipo aqu\u00ed est\u00e1 formado por SIG, ingenieros de ventas e ingenieros de OSP.<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 hace cada uno de esos equipos?<\/strong><\/p>\n\n\n\n<p>GIS son las siglas en ingl\u00e9s de Sistemas de Informaci\u00f3n Geogr\u00e1fica. Se aseguran de que todas las fibras y conductos que instalamos aparecen en los mapas, y de que todos los mapas se ajustan a todo lo construido.<\/p>\n\n\n\n<p>Los ingenieros de ventas visitan las instalaciones de los clientes para determinar c\u00f3mo llevar la fibra y los equipos a sus hogares.<\/p>\n\n\n\n<p>Los ingenieros de la OSP trabajan con empresas de ingenier\u00eda para obtener dise\u00f1os de rutas de fibra, dise\u00f1ar solicitudes de servicio al cliente y trabajar con agencias de permisos para obtener licencias de construcci\u00f3n.<\/p>\n\n\n\n<p><strong>\u00bfCon qu\u00e9 departamentos trabaja fuera de UTOPIA Fiber?<\/strong><\/p>\n\n\n\n<p>Trabajamos con otras empresas de ingenier\u00eda, las ciudades y nuestros contratistas.<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 le hizo decidir que quer\u00eda trabajar para UTOPIA Fiber?<\/strong><\/p>\n\n\n\n<p>Quer\u00eda una nueva oportunidad y pens\u00e9 que ser\u00eda un buen lugar para trabajar.<\/p>\n\n\n\n<p><strong>Fuera del trabajo, \u00bfqu\u00e9 es lo que m\u00e1s le gusta hacer?<\/strong><\/p>\n\n\n\n<p>El ciclismo es lo que m\u00e1s me gusta hacer fuera del trabajo<\/p>\n\n\n\n<p><strong>\u00bfCu\u00e1l es el mayor reto al que se enfrentan sus equipos?<\/strong><\/p>\n\n\n\n<p>El mayor reto son los constantes cambios en el terreno y tener que actualizar los mapas y cambiar las cosas de sitio. Es algo cotidiano, y tenemos que asegurarnos de que las cosas son correctas y precisas.<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 le gustar\u00eda que la gente supiera sobre su departamento en particular?<\/strong><\/p>\n\n\n\n<p>Ojal\u00e1 la gente supiera que tocan a cada cliente y a cada fibra para asegurarse de que podemos encargar los servicios. No se pueden hacer pedidos sin el SIG, y si los mapas est\u00e1n mal, hay muchos problemas. No se puede localizar y no se puede construir bien, as\u00ed que es un trabajo muy importante asegurarse de que todo es exacto.<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 es lo mejor de trabajar en UTOPIA Fiber?<\/strong><\/p>\n\n\n\n<p>Somos un buen equipo. Es como una familia, todos nos llevamos bien y trabajamos juntos.<\/p>\n\n\n\n<p><strong>\u00bfCu\u00e1l ha sido la experiencia m\u00e1s extra\u00f1a que ha vivido en UTOPIA Fiber?<\/strong><\/p>\n\n\n\n<p>\u00bfLa experiencia m\u00e1s extra\u00f1a? Bueno, hemos tenido muchos incendios que han quemado nuestra fibra, esas son algunas de las m\u00e1s raras. Tuvimos un sof\u00e1 que quem\u00f3 nuestra fibra en West Valley City, y hubo una vez un cami\u00f3n que se incendi\u00f3 y quem\u00f3 nuestra fibra. Otro extra\u00f1o fue alguien que dispar\u00f3 a nuestra fibra con una 22.<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 le gustar\u00eda que la gente supiera sobre UTOPIA Fiber?<\/strong><\/p>\n\n\n\n<p>Me gustar\u00eda que la gente supiera que ofrecemos un Internet incre\u00edble y a buen precio. Todas las cosas buenas de UTOPIA. A veces hay ideas equivocadas, as\u00ed que me gustar\u00eda que supieran todo lo bueno.<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 es lo que m\u00e1s le gusta de Internet de fibra \u00f3ptica?<\/strong><\/p>\n\n\n\n<p>A\u00fan no tengo fibra. Vivo en una ciudad que no tiene UTOPIA Fiber, \u00a1pero quiero fibra! La quiero por las velocidades, la fiabilidad y, sobre todo, por las velocidades sim\u00e9tricas de la fibra. Con mi proveedor actual, no tengo eso. Ni por asomo.<\/p>\n\n\n\n<p>Esperamos que hayas disfrutado conociendo a nuestro Director de Ingenier\u00eda de Planta Exterior. Sabemos que no podr\u00edamos hacer lo que hacemos sin el duro trabajo que Brian y su equipo dedican cada d\u00eda a nuestra red de fibra.<\/p>\n\n\n\n<p>\u00bfA qui\u00e9n deber\u00edamos entrevistar ahora? H\u00e1ganos saber en nuestras redes sociales si hay alg\u00fan departamento del que le gustar\u00eda o\u00edr hablar. Puede encontrarnos en <a href=\"https:\/\/twitter.com\/UTOPIAFiber\" data-type=\"URL\" data-id=\"https:\/\/twitter.com\/UTOPIAFiber\" target=\"_blank\" rel=\"noreferrer noopener\">Twitter<\/a>, <a href=\"https:\/\/www.facebook.com\/UTOPIAFiber\" data-type=\"URL\" data-id=\"https:\/\/www.facebook.com\/UTOPIAFiber\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>, <a href=\"https:\/\/www.linkedin.com\/company\/utopia-fiber\/\" data-type=\"URL\" data-id=\"https:\/\/www.linkedin.com\/company\/utopia-fiber\/\" target=\"_blank\" rel=\"noreferrer noopener\">Linkedin<\/a>, <a href=\"https:\/\/www.reddit.com\/r\/UtopiaFiber\/\" data-type=\"URL\" data-id=\"https:\/\/www.reddit.com\/r\/UtopiaFiber\/\" target=\"_blank\" rel=\"noreferrer noopener\">Reddit<\/a>, <a href=\"https:\/\/www.tiktok.com\/@utopiafiber?_t=8aGWO50ory2&amp;_r=1\" data-type=\"URL\" data-id=\"https:\/\/www.tiktok.com\/@utopiafiber?_t=8aGWO50ory2&amp;_r=1\" target=\"_blank\" rel=\"noreferrer noopener\">TikTok<\/a>y <a href=\"https:\/\/www.instagram.com\/utopiafiber\/\" data-type=\"URL\" data-id=\"https:\/\/www.instagram.com\/utopiafiber\/\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>. <\/p>","protected":false},"excerpt":{"rendered":"<p>In today\u2019s interview, we\u2019re talking to our Outside Plant Engineering Manager, Brian Kelsey to get all the details about what it\u2019s like working on the network planning side of UTOPIA Fiber.<\/p>","protected":false},"author":22,"featured_media":13133,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[105,179,96],"tags":[97,98,100,138,186,104,173,165,130,180,131,181,110,187,166,182,188,189,184,119,120,121,122,124,125,170],"class_list":["post-11570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-broadband-efforts","category-explaining-utopia","category-blog","tag-1-gig","tag-10-gigs","tag-100","tag-138","tag-announcement","tag-broadband","tag-fast-internet","tag-fastest-internet","tag-fiber","tag-fiber-installation","tag-fiber-optic","tag-fiber-to-the-home","tag-gbps","tag-internet-news","tag-isp","tag-mbps","tag-monthly-update","tag-news","tag-symmetrical-speeds","tag-utah","tag-utah-fast-internet","tag-utah-internet","tag-utopia","tag-utopia-fiber","tag-utopia-fiber-in-my-area","tag-utopia-fiber-install"],"_links":{"self":[{"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/posts\/11570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/comments?post=11570"}],"version-history":[{"count":1,"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/posts\/11570\/revisions"}],"predecessor-version":[{"id":13136,"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/posts\/11570\/revisions\/13136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/media\/13133"}],"wp:attachment":[{"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/media?parent=11570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/categories?post=11570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/tags?post=11570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}