{"id":11692,"date":"2023-09-18T16:00:58","date_gmt":"2023-09-18T16:00:58","guid":{"rendered":"https:\/\/www.utopiafiber.com\/?p=11692"},"modified":"2024-04-16T09:49:59","modified_gmt":"2024-04-16T09:49:59","slug":"entrevista-con-un-responsable-de-marketing","status":"publish","type":"post","link":"https:\/\/www.utopiafiber.dev\/es\/entrevista-con-un-responsable-de-marketing\/","title":{"rendered":"Entrevista con un Director de Marketing"},"content":{"rendered":"<p>Un nuevo mes significa una nueva entrevista con uno de nuestros incre\u00edbles empleados para conocer en exclusiva los entresijos de la vida en UTOPIA Fiber. Este mes hablamos con nuestra directora de marketing, Lexi Christensen, para que nos cuente c\u00f3mo es trabajar en el equipo de marketing de UTOPIA Fiber.\u00a0<\/p>\n\n\n\n<p><strong>\u00bfC\u00f3mo te llamas, qu\u00e9 cargo ocupas y cu\u00e1nto tiempo llevas en UTOPIA Fiber?<\/strong><\/p>\n\n\n\n<p>Me llamo Lexi Christensen, soy directora de marketing y llevo aqu\u00ed unos siete a\u00f1os y medio.<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 haces como responsable de marketing en UTOPIA Fiber?<\/strong><\/p>\n\n\n\n<p>Gestiono las funciones diarias de marketing. Gestiono nuestras actividades digitales, sociales, eventos, relaciones p\u00fablicas y trabajo mucho con las ciudades y nuestros proveedores de servicios de Internet. Tengo las manos metidas en un poco de todo.<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 le inspir\u00f3 para dedicarse profesionalmente al marketing?<\/strong><\/p>\n\n\n\n<p>En realidad no eleg\u00ed marketing como carrera. Cuando estaba en la universidad, en realidad quer\u00eda estudiar medicina. Quer\u00eda ser oftalm\u00f3loga, pero resulta que odio las matem\u00e1ticas y las ciencias. As\u00ed que hice un giro de 180 grados en la universidad y decid\u00ed dedicarme a las relaciones p\u00fablicas y la publicidad. Lo que me llev\u00f3 al marketing. No estaba realmente inspirada, simplemente sucedi\u00f3.<\/p>\n\n\n\n<p><strong>\u00bfCu\u00e1l es el mayor obst\u00e1culo al que se enfrenta su equipo?<\/strong><\/p>\n\n\n\n<p>Yo dir\u00eda que crecer en nuevas ciudades es un reto. Pero es un buen reto. Cada ciudad es muy diferente, por lo que hay que dirigirse a ellas de forma distinta. Cada ciudad tiene una demograf\u00eda, un ambiente y unos gustos diferentes. As\u00ed que hay que trabajar mucho con ellas. Tenemos que hacer campa\u00f1as para dar a conocer la marca, aunque algunas personas ya sepan qui\u00e9nes somos y otras no, as\u00ed que hay que aprender a desenvolverse en ese entorno. Tambi\u00e9n creo que marketing es el \u00fanico departamento que tiene que saber b\u00e1sicamente lo que hacen todos los dem\u00e1s. Tenemos que saber un poco sobre ingenier\u00eda, el NOC, ventas comerciales, atenci\u00f3n al cliente, FSG, c\u00f3mo fijamos los precios, etc. Tenemos que saber todo eso para hacer bien nuestro trabajo, as\u00ed que trabajamos de forma un poco diferente a los dem\u00e1s departamentos.<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 es lo que m\u00e1s le gusta de trabajar para UTOPIA Fiber?<\/strong><\/p>\n\n\n\n<p>Dir\u00eda que mi parte favorita es que nunca es lo mismo. Cada d\u00eda es diferente. Nunca es mundano, y nunca tengo el mismo d\u00eda dos veces. Cuando llego al trabajo nunca s\u00e9 lo que voy a hacer hoy. Las cosas siempre cambian y son diferentes. Y eso me gusta, me mantiene alerta y evita que me aburra. Creo que por eso he durado tanto aqu\u00ed, porque es divertido. Tambi\u00e9n me gusta mucho la gente de aqu\u00ed. Mi equipo en concreto es el mejor. Cassie se encarga de nuestro marketing digital y es incre\u00edble. Y luego tenemos otra Lexi en el equipo que se encarga de las redes sociales, gr\u00e1ficos y videos que tambi\u00e9n es incre\u00edble. Todas estamos dirigidas por nuestra intr\u00e9pida l\u00edder, Kim, y todas nos compenetramos muy bien y tenemos un equipo de mujeres muy fuerte.&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 cree que hace \u00fanico a UTOPIA Fiber?<\/strong><\/p>\n\n\n\n<p>Bueno, para empezar somos la mayor red de acceso abierto del pa\u00eds, lo que es bastante singular. Creo que somos los \u00fanicos del pa\u00eds que hacemos lo que hacemos a la escala que lo hacemos. Siempre estamos cambiando, siempre nos movemos, siempre crecemos hacia nuevas ciudades y tenemos que relacionarnos con mucha gente diferente. Tenemos montones de ISP en nuestra red con los que trabajamos, y tenemos montones de ciudades diferentes con las que trabajamos. No es s\u00f3lo un producto, tenemos que comercializar ciudades, ISP y todo lo dem\u00e1s. Es el \u00fanico producto del pa\u00eds que hace lo que nosotros hacemos.<\/p>\n\n\n\n<p><strong>\u00bfCu\u00e1l ha sido la experiencia m\u00e1s extra\u00f1a que ha vivido en UTOPIA Fiber?<\/strong><\/p>\n\n\n\n<p>Tengo muchos, as\u00ed que veamos. Probablemente el m\u00e1s reciente fue recoger una vaca de madera en Santa Clara para decorar para un evento, eso fue bastante raro. Estaba all\u00ed con mi madre y mi marido y se me hab\u00eda olvidado. As\u00ed que cuando les mencion\u00e9 que \"Ah, s\u00ed, tengo que ir a recoger una vaca\", se quedaron como \"\u00bfde qu\u00e9 est\u00e1s hablando?\". Una vez que fuimos a buscarla lo entendieron, pero s\u00ed, fue bastante raro. Tambi\u00e9n hicimos fotos de departamento para nuestra jefa por su cumplea\u00f1os. Eran fotos inc\u00f3modas de familia, y las convertimos en un calendario para ella, que fue bastante raro, pero tambi\u00e9n muy divertido.<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 le gustar\u00eda que la gente supiera sobre UTOPIA Fiber?<\/strong><\/p>\n\n\n\n<p>Creo que una de las cosas de las que la gente no se da cuenta es que no somos una empresa privada. Somos lo que se llama una agencia interlocal, as\u00ed que somos propiedad de las ciudades, trabajamos para las ciudades y hacemos las cosas en el mejor inter\u00e9s de esas ciudades.<\/p>\n\n\n\n<p><strong>Fuera del trabajo, \u00bfqu\u00e9 es lo que m\u00e1s le gusta hacer?<\/strong><\/p>\n\n\n\n<p>Me encanta leer. Tambi\u00e9n toco muchos instrumentos y me gusta aprender otros nuevos. As\u00ed que toco mucho y estoy en muchas sinf\u00f3nicas del valle. Me encanta la m\u00fasica.<\/p>\n\n\n\n<p><strong>\u00bfCu\u00e1ntos instrumentos toca?<\/strong><\/p>\n\n\n\n<p>Toco el piano, el viol\u00edn, la viola, la mandolina, el banjo, el ukelele, la guitarra y la flauta, as\u00ed que ocho en total. No soy cantante, pero s\u00e9 tocar algunos instrumentos.<\/p>\n\n\n\n<p><strong>Si se quedara tirado en una isla desierta, \u00bfcon qu\u00e9 equipo, adem\u00e1s del suyo, querr\u00eda quedarse?&nbsp;<\/strong><\/p>\n\n\n\n<p>Depende. Si voy a quedarme varado en esta isla para siempre, me gustar\u00eda estar con gente divertida y entretenida. Que ser\u00eda como nuestro equipo de servicio al cliente, porque son un mot\u00edn. Pero si hay alguna posibilidad de salir de la isla, entonces necesitar\u00eda algunos pensadores realmente l\u00f3gicos e inteligentes, como los ingenieros, que simplemente dijeran \"hag\u00e1moslo y largu\u00e9monos de aqu\u00ed\". Supongo que depende de la situaci\u00f3n.<\/p>\n\n\n\n<p>\u00a1Eso es todo para la entrevista de este mes! Estamos muy agradecidos a Lexi por todo el trabajo duro que ella y su equipo hacen para ayudar a UTOPIA Fiber a crecer. Esperamos que os haya gustado conocerla tanto como a nosotros.<\/p>\n\n\n\n<p>\u00bfA qui\u00e9n deber\u00edamos entrevistar ahora? H\u00e1ganos saber en nuestras redes sociales si hay alg\u00fan departamento del que le gustar\u00eda o\u00edr hablar. Puede encontrarnos en <a href=\"https:\/\/twitter.com\/UTOPIAFiber\" data-type=\"URL\" data-id=\"https:\/\/twitter.com\/UTOPIAFiber\" target=\"_blank\" rel=\"noreferrer noopener\">Twitter<\/a>, <a href=\"https:\/\/www.facebook.com\/UTOPIAFiber\" data-type=\"URL\" data-id=\"https:\/\/www.facebook.com\/UTOPIAFiber\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>, <a href=\"https:\/\/www.linkedin.com\/company\/utopia-fiber\/\" data-type=\"URL\" data-id=\"https:\/\/www.linkedin.com\/company\/utopia-fiber\/\" target=\"_blank\" rel=\"noreferrer noopener\">Linkedin<\/a>, <a href=\"https:\/\/www.reddit.com\/r\/UtopiaFiber\/\" data-type=\"URL\" data-id=\"https:\/\/www.reddit.com\/r\/UtopiaFiber\/\" target=\"_blank\" rel=\"noreferrer noopener\">Reddit<\/a>, <a href=\"https:\/\/www.tiktok.com\/@utopiafiber?_t=8aGWO50ory2&amp;_r=1\" data-type=\"URL\" data-id=\"https:\/\/www.tiktok.com\/@utopiafiber?_t=8aGWO50ory2&amp;_r=1\" target=\"_blank\" rel=\"noreferrer noopener\">TikTok<\/a>y <a href=\"https:\/\/www.instagram.com\/utopiafiber\/\" data-type=\"URL\" data-id=\"https:\/\/www.instagram.com\/utopiafiber\/\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>. <\/p>","protected":false},"excerpt":{"rendered":"<p>Un nuevo mes significa una nueva entrevista con uno de nuestros incre\u00edbles empleados para conocer en exclusiva los entresijos de la vida en UTOPIA Fiber. Este mes hablamos con nuestra directora de marketing, Lexi Christensen, para que nos cuente c\u00f3mo es trabajar en el equipo de marketing de UTOPIA Fiber.\u00a0<\/p>","protected":false},"author":22,"featured_media":13116,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[105,179,96],"tags":[97,98,100,138,186,104,173,165,130,180,131,181,110,187,166,182,188,189,184,119,120,121,122,124,125,170],"class_list":["post-11692","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-broadband-efforts","category-explaining-utopia","category-blog","tag-1-gig","tag-10-gigs","tag-100","tag-138","tag-announcement","tag-broadband","tag-fast-internet","tag-fastest-internet","tag-fiber","tag-fiber-installation","tag-fiber-optic","tag-fiber-to-the-home","tag-gbps","tag-internet-news","tag-isp","tag-mbps","tag-monthly-update","tag-news","tag-symmetrical-speeds","tag-utah","tag-utah-fast-internet","tag-utah-internet","tag-utopia","tag-utopia-fiber","tag-utopia-fiber-in-my-area","tag-utopia-fiber-install"],"_links":{"self":[{"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/posts\/11692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/comments?post=11692"}],"version-history":[{"count":1,"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/posts\/11692\/revisions"}],"predecessor-version":[{"id":13115,"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/posts\/11692\/revisions\/13115"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/media\/13116"}],"wp:attachment":[{"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/media?parent=11692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/categories?post=11692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.utopiafiber.dev\/es\/wp-json\/wp\/v2\/tags?post=11692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}